{"id":5644,"date":"2025-10-16T21:40:38","date_gmt":"2025-10-16T19:40:38","guid":{"rendered":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/?p=5644"},"modified":"2025-11-19T23:04:31","modified_gmt":"2025-11-19T22:04:31","slug":"post-an-die-ratsmitglieder-gemeinsam-fuer-demokratie-in-oberberg","status":"publish","type":"post","link":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/post-an-die-ratsmitglieder-gemeinsam-fuer-demokratie-in-oberberg\/","title":{"rendered":"Post an die Ratsmitglieder: \u201eGemeinsam f\u00fcr Demokratie in Oberberg\u201c"},"content":{"rendered":"\n<p>Wie abzusehen war, ist die rechtsextreme AfD bei der Kommunalwahl im September 2025 auch im Oberbergischen in viele Stadt- und Gemeinder\u00e4te eingezogen (mehr dazu in unserer <a href=\"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2025\/09\/WahlanalyseKommunalwahl2025.pdf\">Wahlanalyse<\/a>). Wie sollen die demokratischen Fraktionen jetzt mit den Rechtsextremen umgehen? Steht die \u201eBrandmauer\u201c?<\/p>\n\n\n\n<p><strong>Wir haben deshalb Anfang Oktober alle demokratischen Rats- und Kreistagsmitglieder (also nicht die der AfD!) im Kreis pers\u00f6nlich angeschrieben \u2013 das waren \u00fcber 400 Briefe!<\/strong><\/p>\n\n\n\n<!--more-->\n\n\n\n<p>Wir haben unsere Sorge um unsere freiheitlich-demokratische Grundordnung und den Erhalt der Menschenw\u00fcrde im Oberbergischen Kreis ge\u00e4u\u00dfert und die Mandatstr\u00e4ger*innen gebeten,<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>sich bei der Aus\u00fcbung ihres Amtes an unseren gemeinsamen Werten und gesellschaftlichen Errungenschaften zu orientieren,<\/li>\n\n\n\n<li>bei allen Unterschieden mit den anderen demokratischen Fraktionen gemeinsam stets nach den besten L\u00f6sungen f\u00fcr die Menschen im Oberbergischen Kreis zu streben und<\/li>\n\n\n\n<li>sich f\u00fcr eine starke Zivilgesellschaft und gegen die Verletzung unserer Werte einzusetzen.<\/li>\n<\/ul>\n\n\n\n<p>Wir haben die Erwartung ge\u00e4u\u00dfert,<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>dass es keine Zusammenarbeit mit der AfD gibt,<\/li>\n\n\n\n<li>dass keine Mehrheiten zustande kommen, die auf die AfD angewiesen sind,<\/li>\n\n\n\n<li> und dass die Fraktionen der \u201eVerlockung\u201c widerstehen, einen Beschluss mit Hilfe der AfD zu erwirken sondern M\u00f6glichkeiten f\u00fcr Mehrheiten ohne die AfD ausloten \u2013 auch wenn das m\u00fchevolle Kompromisse erfordert.<\/li>\n<\/ul>\n\n\n\n<p>Abschlie\u00dfend wurde noch einmal betont, wie wichtig das klare Engagement der demokratischen Ratsmitglieder f\u00fcr die Demokratie ist:<\/p>\n\n\n\n<p>&#8222;Auch wenn wir davon ausgehen, dass sich die Ereignisse von vor mehr als 90 Jahren nicht genauso wiederholen werden, m\u00fcssen wir doch drohenden Gefahren Rechnung tragen. Die AfD greift unsere Werte und gesellschaftlichen Errungenschaften an, wie zum Beispiel mit ihrer Forderung nach \u201eRemigration\u201c von Menschen mit Migrationsgeschichte, mit der Leugnung des Klimawandels oder mit der r\u00fcckw\u00e4rtsgewandten Familienpolitik. Gerade jetzt brauchen wir engagierte Menschen wie Sie, die sich den Angriffen auf die Eckpfeiler unserer Demokratie entgegenstellen.&#8220;<\/p>\n\n\n\n<p>Auch die B\u00fcrgermeisterinnen und B\u00fcrgermeister sowie der Landrat haben \u2013 mit einem etwas ver\u00e4nderten Text \u2013 Post von uns bekommen . Diese sind zwar zur parteipolitischen Neutralit\u00e4t verpflichtet, wir haben sie aber gebeten, mit daf\u00fcr zu sorgen, dass die Rechtsextremen unsere Gesellschaft nicht spalten und die M\u00f6glichkeiten f\u00fcr Mehrheiten ohne die AfD zu f\u00f6rdern.<\/p>\n\n\n\n<p>F\u00fcr die Ratsmitglieder in Engelskirchen und Lindlar, wo die AfD nicht antreten konnte, haben wir den Text nat\u00fcrlich entsprechend ge\u00e4ndert und Ratsmitglieder und B\u00fcrgermeister aufgefordert, das Engagement der Zivilgesellschaft f\u00fcr Demokratie und Zusammenhalt weiter zu unterst\u00fctzen.<\/p>\n\n\n\n<p>Es gibt schon einige R\u00fcckmeldungen zu unserem Brief \u2013 durchweg positiv. Wir werden die Politik im Kreistag und in den Stadt- und Gemeinder\u00e4ten in den n\u00e4chsten Monaten aufmerksam beobachten und begleiten.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wie abzusehen war, ist die rechtsextreme AfD bei der Kommunalwahl im September 2025 auch im Oberbergischen in viele Stadt- und Gemeinder\u00e4te eingezogen (mehr dazu in unserer Wahlanalyse). Wie sollen die demokratischen Fraktionen jetzt mit den Rechtsextremen umgehen? Steht die \u201eBrandmauer\u201c? Wir haben deshalb Anfang Oktober alle demokratischen Rats- und Kreistagsmitglieder (also nicht die der AfD!) [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,12,3,1],"tags":[],"class_list":["post-5644","post","type-post","status-publish","format-standard","hentry","category-afd","category-aktiv-gegen-rechts","category-aktuelles","category-allgemein"],"_links":{"self":[{"href":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-json\/wp\/v2\/posts\/5644","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-json\/wp\/v2\/comments?post=5644"}],"version-history":[{"count":4,"href":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-json\/wp\/v2\/posts\/5644\/revisions"}],"predecessor-version":[{"id":5790,"href":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-json\/wp\/v2\/posts\/5644\/revisions\/5790"}],"wp:attachment":[{"href":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-json\/wp\/v2\/media?parent=5644"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-json\/wp\/v2\/categories?post=5644"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-json\/wp\/v2\/tags?post=5644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}