{"id":5559,"date":"2025-09-15T08:30:11","date_gmt":"2025-09-15T06:30:11","guid":{"rendered":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/?p=5559"},"modified":"2025-11-10T18:15:24","modified_gmt":"2025-11-10T17:15:24","slug":"jetzt-muessen-die-demokratinnen-zusammenhalten","status":"publish","type":"post","link":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/jetzt-muessen-die-demokratinnen-zusammenhalten\/","title":{"rendered":"Jetzt m\u00fcssen die Demokrat*innen zusammenhalten!"},"content":{"rendered":"\n<p>15. September 2025, 8 Uhr: <\/p>\n\n\n\n<p>Inzwischen stehen die Sitzverteilungen fest. Im Kreistag kann die bisherige Mehrheit aus CDU, FDP und Freien W\u00e4hlern nicht so weiter machen wie bisher. Jetzt kommt es darauf an, dass alle demokratischen Parteien gemeinsam beraten, wie sie eine Politik f\u00fcr die Menschen im Oberbergischen machen. Eines muss klar sein: <strong>Eine Zusammenarbeit mit der AfD darf es nicht geben! Weder im Kreistag noch in den Stadt- und Gemeinder\u00e4ten!<\/strong> Auch dort muss die CDU mit SPD und Gr\u00fcnen gemeinsam <strong>klare Kante gegen Rechts<\/strong> zeigen. Die demokratischen Fraktionen m\u00fcssen zeigen: Wir k\u00f6nnen uns bei Sachthemen einigen. Antr\u00e4ge der AfD d\u00fcrfen keine politische Bedeutung bekommen. Denen, die sie gew\u00e4hlt haben, muss deutlich gemacht werden: Die AfD erh\u00e4lt bei uns keine M\u00f6glichkeit zu wirken!  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>15. September 2025, 8 Uhr: Inzwischen stehen die Sitzverteilungen fest. Im Kreistag kann die bisherige Mehrheit aus CDU, FDP und Freien W\u00e4hlern nicht so weiter machen wie bisher. Jetzt kommt es darauf an, dass alle demokratischen Parteien gemeinsam beraten, wie sie eine Politik f\u00fcr die Menschen im Oberbergischen machen. Eines muss klar sein: Eine Zusammenarbeit [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,12,3,1],"tags":[],"class_list":["post-5559","post","type-post","status-publish","format-standard","hentry","category-afd","category-aktiv-gegen-rechts","category-aktuelles","category-allgemein"],"_links":{"self":[{"href":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-json\/wp\/v2\/posts\/5559","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-json\/wp\/v2\/comments?post=5559"}],"version-history":[{"count":1,"href":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-json\/wp\/v2\/posts\/5559\/revisions"}],"predecessor-version":[{"id":5560,"href":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-json\/wp\/v2\/posts\/5559\/revisions\/5560"}],"wp:attachment":[{"href":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-json\/wp\/v2\/media?parent=5559"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-json\/wp\/v2\/categories?post=5559"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-json\/wp\/v2\/tags?post=5559"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}