{"id":2813,"date":"2023-12-09T20:41:57","date_gmt":"2023-12-09T19:41:57","guid":{"rendered":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/?p=2813"},"modified":"2023-12-09T20:54:07","modified_gmt":"2023-12-09T19:54:07","slug":"lesung-der-menschenrechte","status":"publish","type":"post","link":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/lesung-der-menschenrechte\/","title":{"rendered":"Lesung der Menschenrechte"},"content":{"rendered":"\n<p class=\"has-medium-font-size\">Aus Anlass des 75. Jahrestags der Erkl\u00e4rung der Menschenrechte haben wir am Samstag, den 9.12.2023, die 30 Artikel der UN-Menschenrechtserkl\u00e4rung in Gummersbach auf dem Lindenplatz verlesen.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"254\" src=\"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/alle-k-1024x254.jpg\" alt=\"\" class=\"wp-image-2814\" srcset=\"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/alle-k-1024x254.jpg 1024w, https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/alle-k-300x74.jpg 300w, https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/alle-k-768x190.jpg 768w, https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/alle-k-1536x381.jpg 1536w, https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/alle-k.jpg 2000w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Ein breites Spektrum aus dem Oberbergischen machte deutlich, dass uns unsere Gesellschaft nicht egal ist. Dabei waren Vertreterinnen und Vertreter aus FDP, B\u00fcndnis90\/Die Gr\u00fcnen und der SPD (bei uns scheint die Ampel zu funktionieren), die Religionsgemeinschaften waren beteiligt: die katholische Kirche, die evangelische Kirche, die freikirchliche Gemeinde Gummersbach-Windhagen und die anglikanische Kirche, die Gewerkschaften waren vertreten &#8211; und es waren viele dabei, die einfach so f\u00fcr die Menschenrechte eintreten, \u201eweil der Mensch ein Mensch ist\u201c (wie Brecht es formulierte).<\/p>\n\n\n\n<!--more-->\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\" style=\"grid-template-columns:25% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"584\" height=\"740\" src=\"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/1.jpg\" alt=\"\" class=\"wp-image-2815 size-full\" srcset=\"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/1.jpg 584w, https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/1-237x300.jpg 237w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-medium-font-size\"><strong>Artikel 1<\/strong> (gelesen von Klaus Jochen Rodenbeck)<br>Alle Menschen sind frei und gleich an W\u00fcrde und Rechten geboren. Sie sind mit Vernunft und Gewissen begabt und sollen einander im Geiste der Br\u00fcderlichkeit begegnen.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\" style=\"grid-template-columns:25% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"624\" height=\"832\" src=\"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/2.jpg\" alt=\"\" class=\"wp-image-2816 size-full\" srcset=\"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/2.jpg 624w, https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/2-225x300.jpg 225w\" sizes=\"auto, (max-width: 624px) 100vw, 624px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p style=\"font-size:20px\"><strong>Artikel 2<\/strong> (gelesen von Stephan Eucken)<br>Jeder hat Anspruch auf alle in dieser Erkl\u00e4rung verk\u00fcndeten Rechte und Freiheiten, ohne irgendeinen Unterschied, etwa nach Rasse, Hautfarbe, Geschlecht, Sprache, Religion, politischer oder sonstiger Anschauung, nationaler oder sozialer Herkunft, Verm\u00f6gen, Geburt oder sonstigem Stand.<br>Des weiteren darf kein Unterschied gemacht werden auf Grund der politischen, rechtlichen oder internationalen Stellung des Landes oder Gebietes, dem eine Person angeh\u00f6rt, gleichg\u00fcltig ob dieses unabh\u00e4ngig ist, unter Treuhandschaft steht, keine Selbstregierung besitzt oder sonst in seiner Souver\u00e4nit\u00e4t eingeschr\u00e4nkt ist.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\" style=\"grid-template-columns:25% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"812\" src=\"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/3.jpg\" alt=\"\" class=\"wp-image-2817 size-full\" srcset=\"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/3.jpg 576w, https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/3-213x300.jpg 213w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-medium-font-size\"><strong>Artikel 3<\/strong> (gelesen von Michael Enders)<br>Jeder hat das Recht auf Leben, Freiheit und Sicherheit der Person.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\" style=\"grid-template-columns:25% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"604\" height=\"708\" src=\"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/4.jpg\" alt=\"\" class=\"wp-image-2818 size-full\" srcset=\"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/4.jpg 604w, https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/4-256x300.jpg 256w\" sizes=\"auto, (max-width: 604px) 100vw, 604px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-medium-font-size\"><strong>Artikel 4<\/strong> (gelesen von Aziz Kocyigit)<br>Niemand darf in Sklaverei oder Leibeigenschaft gehalten werden; Sklaverei und Sklavenhandel in allen ihren Formen sind verboten.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\" style=\"grid-template-columns:25% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"616\" src=\"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/5.jpg\" alt=\"\" class=\"wp-image-2819 size-full\" srcset=\"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/5.jpg 512w, https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/5-249x300.jpg 249w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-medium-font-size\"><strong>Artikel 5<\/strong> (gelesen von Iris Traudisch)<br>Niemand darf der Folter oder grausamer, unmenschlicher oder erniedrigender Behandlung oder Strafe unterworfen werden.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\" style=\"grid-template-columns:25% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"492\" height=\"596\" src=\"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/6.jpg\" alt=\"\" class=\"wp-image-2820 size-full\" srcset=\"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/6.jpg 492w, https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/6-248x300.jpg 248w\" sizes=\"auto, (max-width: 492px) 100vw, 492px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-medium-font-size\"><strong>Artikel 6<\/strong> (gelesen von Konrad Gerards)<br>Jeder hat das Recht, \u00fcberall als rechtsf\u00e4hig anerkannt zu werden.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\" style=\"grid-template-columns:25% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"608\" src=\"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/7.jpg\" alt=\"\" class=\"wp-image-2821 size-full\" srcset=\"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/7.jpg 512w, https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/7-253x300.jpg 253w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-medium-font-size\"><strong>Artikel 7<\/strong> (gelesen von Monica Buchfeld)<br>Alle Menschen sind vor dem Gesetz gleich und haben ohne Unterschied Anspruch auf gleichen Schutz durch das Gesetz. Alle haben Anspruch auf gleichen Schutz gegen jede Diskriminierung, die gegen diese Erkl\u00e4rung verst\u00f6\u00dft, und gegen jede Aufhetzung zu einer derartigen Diskriminierung.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\" style=\"grid-template-columns:24% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"632\" src=\"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/8.jpg\" alt=\"\" class=\"wp-image-2822 size-full\" srcset=\"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/8.jpg 480w, https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/8-228x300.jpg 228w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-medium-font-size\"><strong>Artikel 8<\/strong> (gelesen von Monika Leipelt)<br>Jeder hat Anspruch auf einen wirksamen Rechtsbehelf bei den zust\u00e4ndigen innerstaatlichen Gerichten gegen Handlungen, durch die seine ihm nach der Verfassung oder nach dem Gesetz zustehenden Grundrechte verletzt werden.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\" style=\"grid-template-columns:25% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"544\" height=\"684\" src=\"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/9.jpg\" alt=\"\" class=\"wp-image-2823 size-full\" srcset=\"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/9.jpg 544w, https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/9-239x300.jpg 239w\" sizes=\"auto, (max-width: 544px) 100vw, 544px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-medium-font-size\"><strong>Artikel 9<\/strong> (gelesen von Wilfried Hesseler)<br>Niemand darf willk\u00fcrlich festgenommen, in Haft gehalten oder des Landes verwiesen werden.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\" style=\"grid-template-columns:25% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"516\" height=\"596\" src=\"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/10.jpg\" alt=\"\" class=\"wp-image-2825 size-full\" srcset=\"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/10.jpg 516w, https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/10-260x300.jpg 260w\" sizes=\"auto, (max-width: 516px) 100vw, 516px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-medium-font-size\"><strong>Artikel 10<\/strong> (gelesen von Dominik Trautmann)<br>Jeder hat bei der Feststellung seiner Rechte und Pflichten sowie bei einer gegen ihn erhobenen strafrechtlichen Beschuldigung in voller Gleichheit Anspruch auf ein gerechtes und \u00f6ffentliches Verfahren vor einem unabh\u00e4ngigen und unparteiischen Gericht.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\" style=\"grid-template-columns:25% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"544\" height=\"668\" src=\"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/11.jpg\" alt=\"\" class=\"wp-image-2826 size-full\" srcset=\"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/11.jpg 544w, https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/11-244x300.jpg 244w\" sizes=\"auto, (max-width: 544px) 100vw, 544px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p style=\"font-size:19px\"><strong>Artikel 11<\/strong> (gelesen von Uwe Brustmeier)<br>(1) Jeder, der einer strafbaren Handlung beschuldigt wird, hat das Recht, als unschuldig zu gelten, solange seine Schuld nicht in einem \u00f6ffentlichen Verfahren, in dem er alle f\u00fcr seine Verteidigung notwendigen Garantien gehabt hat, gem\u00e4\u00df dem Gesetz nachgewiesen ist.<br>(2) Niemand darf wegen einer Handlung oder Unterlassung verurteilt werden, die zur Zeit ihrer Begehung nach innerstaatlichem oder internationalem Recht nicht strafbar war. Ebenso darf keine schwerere Strafe als die zum Zeitpunkt der Begehung der strafbaren Handlung angedrohte Strafe verh\u00e4ngt werden.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\" style=\"grid-template-columns:25% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"412\" height=\"532\" src=\"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/12.jpg\" alt=\"\" class=\"wp-image-2827 size-full\" srcset=\"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/12.jpg 412w, https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/12-232x300.jpg 232w\" sizes=\"auto, (max-width: 412px) 100vw, 412px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-medium-font-size\"><strong>Artikel 12<\/strong> (gelesen von Doris Klaka)<br>Niemand darf willk\u00fcrlichen Eingriffen in sein Privatleben, seine Familie, seine Wohnung und seinen Schriftverkehr oder Beeintr\u00e4chtigungen seiner Ehre und seines Rufes ausgesetzt werden. Jeder hat Anspruch auf rechtlichen Schutz gegen solche Eingriffe oder Beeintr\u00e4chtigungen.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\" style=\"grid-template-columns:25% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"600\" src=\"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/13.jpg\" alt=\"\" class=\"wp-image-2828 size-full\" srcset=\"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/13.jpg 480w, https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/13-240x300.jpg 240w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-medium-font-size\"><strong>Artikel 13<\/strong> (gelesen von Nadine Lind\u00f6rfer)<br>(1) Jeder hat das Recht, sich innerhalb eines Staates frei zu bewegen und seinen Aufenthaltsort frei zu w\u00e4hlen.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">(2) Jeder hat das Recht, jedes Land, einschlie\u00dflich seines eigenen, zu verlassen und in sein Land zur\u00fcckzukehren.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\" style=\"grid-template-columns:25% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"488\" height=\"536\" src=\"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/14.jpg\" alt=\"\" class=\"wp-image-2829 size-full\" srcset=\"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/14.jpg 488w, https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/14-273x300.jpg 273w\" sizes=\"auto, (max-width: 488px) 100vw, 488px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p style=\"font-size:22px\"><strong>Artikel 14<\/strong> (gelesen von Dieter Br\u00fcser)<br>(1) Jeder hat das Recht, in anderen L\u00e4ndern vor Verfolgung Asyl zu suchen und zu genie\u00dfen.<br>(2) Dieses Recht kann nicht in Anspruch genommen werden im Falle einer Strafverfolgung, die tats\u00e4chlich auf Grund von Verbrechen nichtpolitischer Art oder auf Grund von Handlungen erfolgt, die gegen die Ziele und Grunds\u00e4tze der Vereinten Nationen versto\u00dfen.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\" style=\"grid-template-columns:25% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"592\" height=\"676\" src=\"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/15.jpg\" alt=\"\" class=\"wp-image-2830 size-full\" srcset=\"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/15.jpg 592w, https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/15-263x300.jpg 263w\" sizes=\"auto, (max-width: 592px) 100vw, 592px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-medium-font-size\"><strong>Artikel 15<\/strong> (gelesen von Christph Bersch)<br>(1) Jeder hat das Recht auf eine Staatsangeh\u00f6rigkeit.<br>(2) Niemandem darf seine Staatsangeh\u00f6rigkeit willk\u00fcrlich entzogen noch das Recht versagt werden, seine Staatsangeh\u00f6rigkeit zu wechseln.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\" style=\"grid-template-columns:25% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"596\" src=\"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/16.jpg\" alt=\"\" class=\"wp-image-2831 size-full\" srcset=\"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/16.jpg 576w, https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/16-290x300.jpg 290w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p style=\"font-size:20px\"><strong>Artikel 16<\/strong> (gelesen von Gerd Wilden)<br>(1) Heiratsf\u00e4hige M\u00e4nner und Frauen haben ohne jede Beschr\u00e4nkung auf Grund der Rasse, der Staatsangeh\u00f6rigkeit oder der Religion das Recht, zu heiraten und eine Familie zu gr\u00fcnden. Sie haben bei der Eheschlie\u00dfung, w\u00e4hrend der Ehe und bei deren Aufl\u00f6sung gleiche Rechte.<br>(2) Eine Ehe darf nur bei freier und uneingeschr\u00e4nkter Willenseinigung der k\u00fcnftigen Ehegatten geschlossen werden.<br>(3) Die Familie ist die nat\u00fcrliche Grundeinheit der Gesellschaft und hat Anspruch auf Schutz durch Gesellschaft und Staat.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\" style=\"grid-template-columns:25% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"484\" height=\"532\" src=\"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/17.jpg\" alt=\"\" class=\"wp-image-2832 size-full\" srcset=\"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/17.jpg 484w, https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/17-273x300.jpg 273w\" sizes=\"auto, (max-width: 484px) 100vw, 484px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-medium-font-size\"><strong>Artikel 17<\/strong> (gelesen von Manfrd Pawlowski)<br>(1) Jeder hat das Recht, sowohl allein als auch in Gemeinschaft mit anderen Eigentum innezuhaben.<br>(2) Niemand darf willk\u00fcrlich seines Eigentums beraubt werden.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\" style=\"grid-template-columns:25% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"592\" height=\"648\" src=\"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/18.jpg\" alt=\"\" class=\"wp-image-2833 size-full\" srcset=\"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/18.jpg 592w, https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/18-274x300.jpg 274w\" sizes=\"auto, (max-width: 592px) 100vw, 592px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p style=\"font-size:22px\"><strong>Artikel 18<\/strong> (gelesen von Markus Aust)<br>Jeder hat das Recht auf Gedanken-, Gewissens- und Religionsfreiheit; dieses Recht schlie\u00dft die Freiheit ein, seine Religion oder seine Weltanschauung zu wechseln, sowie die Freiheit, seine Religion oder seine Weltanschauung allein oder in Gemeinschaft mit anderen, \u00f6ffentlich oder privat durch Lehre, Aus\u00fcbung, Gottesdienst und Kulthandlungen zu bekennen.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\" style=\"grid-template-columns:25% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"476\" height=\"568\" src=\"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/19.jpg\" alt=\"\" class=\"wp-image-2834 size-full\" srcset=\"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/19.jpg 476w, https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/19-251x300.jpg 251w\" sizes=\"auto, (max-width: 476px) 100vw, 476px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-medium-font-size\"><strong>Artikel 19<\/strong> (gelesen von Ina Albowitz-Freytag)<br>Jeder hat das Recht auf Meinungsfreiheit und freie Meinungs\u00e4u\u00dferung; dieses Recht schlie\u00dft die Freiheit ein, Meinungen ungehindert anzuh\u00e4ngen sowie \u00fcber Medien jeder Art und ohne R\u00fccksicht auf Grenzen Informationen und Gedankengut zu suchen, zu empfangen und zu verbreiten.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\" style=\"grid-template-columns:25% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"504\" height=\"544\" src=\"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/20.jpg\" alt=\"\" class=\"wp-image-2835 size-full\" srcset=\"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/20.jpg 504w, https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/20-278x300.jpg 278w\" sizes=\"auto, (max-width: 504px) 100vw, 504px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-medium-font-size\"><strong>Artikel 20<\/strong> (gelesen von Andrea Klingler)<br>(1) Alle Menschen haben das Recht, sich friedlich zu versammeln und zu Vereinigungen zusammenzuschlie\u00dfen.<br>(2) Niemand darf gezwungen werden, einer Vereinigung anzugeh\u00f6ren.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\" style=\"grid-template-columns:25% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"640\" src=\"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/21.jpg\" alt=\"\" class=\"wp-image-2836 size-full\" srcset=\"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/21.jpg 512w, https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/21-240x300.jpg 240w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p style=\"font-size:19px\"><strong>Artikel 21<\/strong> (gelesen von J\u00f6rg Mehlhorn)<br>(1) Jeder hat das Recht, an der Gestaltung der \u00f6ffentlichen Angelegenheiten seines Landes unmittelbar oder durch frei gew\u00e4hlte Vertreter mitzuwirken.<br>(2) Jeder hat das Recht auf gleichen Zugang zu \u00f6ffentlichen \u00c4mtern in seinem Lande.<br>(3) Der Wille des Volkes bildet die Grundlage f\u00fcr die Autorit\u00e4t der \u00f6ffentlichen Gewalt; dieser Wille mu\u00df durch regelm\u00e4\u00dfige, unverf\u00e4lschte, allgemeine und gleiche Wahlen mit geheimer Stimmabgabe oder einem gleichwertigen freien Wahlverfahren zum Ausdruck kommen.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\" style=\"grid-template-columns:25% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"492\" height=\"636\" src=\"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/22.jpg\" alt=\"\" class=\"wp-image-2837 size-full\" srcset=\"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/22.jpg 492w, https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/22-232x300.jpg 232w\" sizes=\"auto, (max-width: 492px) 100vw, 492px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p style=\"font-size:20px\"><strong>Artikel 22<\/strong> (gelesen von Henrik K\u00f6stering)<br>Jeder hat als Mitglied der Gesellschaft das Recht auf soziale Sicherheit und Anspruch darauf, durch innerstaatliche Ma\u00dfnahmen und internationale Zusammenarbeit sowie unter Ber\u00fccksichtigung der Organisation und der Mittel jedes Staates in den Genu\u00df der wirtschaftlichen, sozialen und kulturellen Rechte zu gelangen, die f\u00fcr seine W\u00fcrde und die freie Entwicklung seiner Pers\u00f6nlichkeit unentbehrlich sind.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\" style=\"grid-template-columns:25% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"464\" height=\"540\" src=\"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/23-1.jpg\" alt=\"\" class=\"wp-image-2839 size-full\" srcset=\"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/23-1.jpg 464w, https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/23-1-258x300.jpg 258w\" sizes=\"auto, (max-width: 464px) 100vw, 464px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p style=\"font-size:19px\"><strong>Artikel 23<\/strong> (gelesen von Marc Zimmermann)<br>(1) Jeder hat das Recht auf Arbeit, auf freie Berufswahl, auf gerechte und befriedigende Arbeitsbedingungen sowie auf Schutz vor Arbeitslosigkeit.<br>(2) Jeder, ohne Unterschied, hat das Recht auf gleichen Lohn f\u00fcr gleiche Arbeit.<br>(3) Jeder, der arbeitet, hat das Recht auf gerechte und befriedigende Entlohnung, die ihm und seiner Familie eine der menschlichen W\u00fcrde entsprechende Existenz sichert, gegebenenfalls erg\u00e4nzt durch andere soziale Schutzma\u00dfnahmen.<br>(4) Jeder hat das Recht, zum Schutze seiner Interessen Gewerkschaften zu bilden und solchen beizutreten.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\" style=\"grid-template-columns:25% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"392\" height=\"500\" src=\"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/24.jpg\" alt=\"\" class=\"wp-image-2840 size-full\" srcset=\"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/24.jpg 392w, https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/24-235x300.jpg 235w\" sizes=\"auto, (max-width: 392px) 100vw, 392px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-medium-font-size\"><strong>Artikel 24 <\/strong>(gelesen von Kim Schr\u00f6ter)<br>Jeder hat das Recht auf Erholung und Freizeit und insbesondere auf eine vern\u00fcnftige Begrenzung der Arbeitszeit und regelm\u00e4\u00dfigen bezahlten Urlaub.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\" style=\"grid-template-columns:25% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"448\" height=\"492\" src=\"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/25.jpg\" alt=\"\" class=\"wp-image-2841 size-full\" srcset=\"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/25.jpg 448w, https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/25-273x300.jpg 273w\" sizes=\"auto, (max-width: 448px) 100vw, 448px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p style=\"font-size:19px\"><strong>Artikel 25<\/strong> (gelesen von Heidi Mehlhorn)<br>(1) Jeder hat das Recht auf einen Lebensstandard, der seine und seiner Familie<br>Gesundheit und Wohl gew\u00e4hrleistet, einschlie\u00dflich Nahrung, Kleidung, Wohnung, \u00e4rztliche Versorgung und notwendige soziale Leistungen, sowie das Recht auf Sicherheit im Falle von Arbeitslosigkeit, Krankheit, Invalidit\u00e4t oder Verwitwung, im Alter sowie bei anderweitigem Verlust seiner Unterhaltsmittel durch unverschuldete Umst\u00e4nde.<br>(2) M\u00fctter und Kinder haben Anspruch auf besondere F\u00fcrsorge und  Unterst\u00fctzung. Alle Kinder, eheliche wie au\u00dfereheliche, genie\u00dfen den gleichen sozialen Schutz.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\" style=\"grid-template-columns:25% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"464\" height=\"544\" src=\"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/26.jpg\" alt=\"\" class=\"wp-image-2842 size-full\" srcset=\"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/26.jpg 464w, https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/26-256x300.jpg 256w\" sizes=\"auto, (max-width: 464px) 100vw, 464px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p style=\"font-size:18px\"><strong>Artikel 26<\/strong> (gelesen von Ekkehard St\u00f6ber)<br>(1) Jeder hat das Recht auf Bildung. Die Bildung ist unentgeltlich, zum mindesten der  Grundschulunterricht und die grundlegende Bildung. Der Grundschulunterricht ist obligatorisch. Fach- und Berufsschulunterricht m\u00fcssen allgemein verf\u00fcgbar gemacht werden, und der Hochschulunterricht mu\u00df allen gleicherma\u00dfen entsprechend ihren F\u00e4higkeiten offenstehen.<br>(2) Die Bildung mu\u00df auf die volle Entfaltung der menschlichen Pers\u00f6nlichkeit und auf die St\u00e4rkung der Achtung vor den Menschenrechten und Grundfreiheiten gerichtet sein. Sie mu\u00df zu Verst\u00e4ndnis, Toleranz und Freundschaft zwischen allen Nationen und allen rassischen oder religi\u00f6sen Gruppen beitragen und der T\u00e4tigkeit der Vereinten Nationen f\u00fcr die Wahrung des Friedens f\u00f6rderlich sein.<br>(3) Die Eltern haben ein vorrangiges Recht, die Art der Bildung zu w\u00e4hlen, die ihren Kindern zuteil werden soll.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\" style=\"grid-template-columns:25% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"536\" height=\"584\" src=\"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/27.jpg\" alt=\"\" class=\"wp-image-2843 size-full\" srcset=\"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/27.jpg 536w, https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/27-275x300.jpg 275w\" sizes=\"auto, (max-width: 536px) 100vw, 536px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p style=\"font-size:22px\"><strong>Artikel 27<\/strong> (gelesen von Ulrich Wagner)<br>(1) Jeder hat das Recht, am kulturellen Leben der Gemeinschaft frei teilzunehmen, sich an den K\u00fcnsten zu erfreuen und am wissenschaftlichen Fortschritt und dessen Errungenschaften teilzuhaben.<br>(2) Jeder hat das Recht auf Schutz der geistigen und materiellen Interessen, die ihm als Urheber von Werken der Wissenschaft, Literatur oder Kunst erwachsen.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\" style=\"grid-template-columns:25% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"528\" height=\"616\" src=\"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/28.jpg\" alt=\"\" class=\"wp-image-2844 size-full\" srcset=\"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/28.jpg 528w, https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/28-257x300.jpg 257w\" sizes=\"auto, (max-width: 528px) 100vw, 528px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-medium-font-size\"><strong>Artikel 28<\/strong> (gelesen von Gabriele Dreistein)<br>Jeder hat Anspruch auf eine soziale und internationale Ordnung, in der die in dieser Erkl\u00e4rung verk\u00fcndeten Rechte und Freiheiten voll verwirklicht werden k\u00f6nnen.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\" style=\"grid-template-columns:25% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"396\" height=\"496\" src=\"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/29.jpg\" alt=\"\" class=\"wp-image-2845 size-full\" srcset=\"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/29.jpg 396w, https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/29-240x300.jpg 240w\" sizes=\"auto, (max-width: 396px) 100vw, 396px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p style=\"font-size:19px\"><strong>Artikel 29<\/strong> (gelesen von Ute Radermacher)<br>(1) Jeder hat Pflichten gegen\u00fcber der Gemeinschaft, in der allein die freie und volle Entfaltung seiner Pers\u00f6nlichkeit m\u00f6glich ist.<br>(2) Jeder ist bei der Aus\u00fcbung seiner Rechte und Freiheiten nur den Beschr\u00e4nkungen unterworfen, die das Gesetz ausschlie\u00dflich zu dem Zweck vorsieht, die Anerkennung und Achtung der Rechte und Freiheiten anderer zu sichern und den gerechten Anforderungen der Moral, der \u00f6ffentlichen Ordnung und des allgemeinen Wohles in einer demokratischen Gesellschaft zu gen\u00fcgen.<br>(3) Diese Rechte und Freiheiten d\u00fcrfen in keinem Fall im Widerspruch zu den Zielen und Grunds\u00e4tzen der Vereinten Nationen ausge\u00fcbt werden.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\" style=\"grid-template-columns:25% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"452\" height=\"508\" src=\"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/30.jpg\" alt=\"\" class=\"wp-image-2846 size-full\" srcset=\"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/30.jpg 452w, https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/30-267x300.jpg 267w\" sizes=\"auto, (max-width: 452px) 100vw, 452px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-medium-font-size\"><strong>Artikel 30 <\/strong>(gelesen von Annedore Reich-Brinkmann)<br>Keine Bestimmung dieser Erkl\u00e4rung darf dahin ausgelegt werden, da\u00df sie f\u00fcr einen Staat, eine Gruppe oder eine Person irgendein Recht begr\u00fcndet, eine T\u00e4tigkeit auszu\u00fcben oder eine Handlung zu begehen, welche die Beseitigung der in dieser Erkl\u00e4rung verk\u00fcndeten Rechte und Freiheiten zum Ziel hat.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile is-vertically-aligned-center\" style=\"grid-template-columns:20% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"961\" height=\"1024\" src=\"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/gj-961x1024.jpg\" alt=\"\" class=\"wp-image-2847 size-full\" srcset=\"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/gj-961x1024.jpg 961w, https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/gj-281x300.jpg 281w, https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/gj-768x819.jpg 768w, https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2023\/12\/gj.jpg 1032w\" sizes=\"auto, (max-width: 961px) 100vw, 961px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p style=\"font-size:20px\"><strong>Schlusswort<\/strong> von Gerhard Jenders<\/p>\n\n\n\n<p style=\"font-size:18px\">Vielen Dank! Das war die Allgemeine Erkl\u00e4rung der Menschenrechte. Zu jedem Artikel k\u00f6nnte man noch so viel sagen: Wird der eingehalten? Bei uns? In Europa? In der Welt? Was kann ich tun? Ich muss da insbesondere an den Artikel 14 denken: \u201eJeder hat das Recht, in anderen L\u00e4ndern vor Verfolgung Asyl zu suchen und zu erhalten.\u201c Wird der eingehalten? Bei uns? In Europa? In der Welt? Was kann ich tun?<br>Wie geht es weiter? Ich zitiere noch einmal aus der Pr\u00e4ambel: \u201ealle Organe der Gesellschaft sollen sich diese Erkl\u00e4rung stets gegenw\u00e4rtig halten\u201c<br>Die Organe der Gesellschaft \u2013 das sind wir! Wir sind aufgerufen, f\u00fcr die Menschenrechte einzutreten. Im privaten Umfeld, in der \u00d6ffentlichkeit, in unserem Land und weltweit. Wir sind es, die klarmachen m\u00fcssen: Eine Verletzung der Menschenrechte nehmen wir nicht hin \u2013 weder die Verletzung unserer eigenen Rechte noch die Diskriminierung, Ausgrenzung, Verfolgung anderer. Es gibt viele M\u00f6glichkeiten, aktiv zu sein. Wir d\u00fcrfen nicht nachlassen. Denn wenn wir nichts tun \u2013 wer macht es dann?<br>Mir hat diese gemeinsame Aktion Spa\u00df gemacht, denn sie hat uns allen gezeigt: Wir sind nicht allein in unserem Engagement. Lasst uns daf\u00fcr sorgen, dass wir noch mehr werden. Wir brauchen Mitmenschen, die sich engagieren \u2013 f\u00fcr unsere Zukunft, f\u00fcr die Zukunft unserer  Welt. Das n\u00e4chste Jahr bietet viele M\u00f6glichkeiten dazu: Unser Grundgesetz wird 75 Jahre alt, auch da sind wichtige Artikel, auf deren Einhaltung wir immer wieder dringen m\u00fcssen. Und Anfang Juni wird das EU-Parlament neu gew\u00e4hlt \u2013 wir m\u00fcssen gemeinsam daf\u00fcr k\u00e4mpfen, dass unser Kontinent demokratisch bleibt. Wir sehen uns!<\/p>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Aus Anlass des 75. Jahrestags der Erkl\u00e4rung der Menschenrechte haben wir am Samstag, den 9.12.2023, die 30 Artikel der UN-Menschenrechtserkl\u00e4rung in Gummersbach auf dem Lindenplatz verlesen. Ein breites Spektrum aus dem Oberbergischen machte deutlich, dass uns unsere Gesellschaft nicht egal ist. Dabei waren Vertreterinnen und Vertreter aus FDP, B\u00fcndnis90\/Die Gr\u00fcnen und der SPD (bei uns [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2813","post","type-post","status-publish","format-standard","hentry","category-allgemein"],"_links":{"self":[{"href":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-json\/wp\/v2\/posts\/2813","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-json\/wp\/v2\/comments?post=2813"}],"version-history":[{"count":4,"href":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-json\/wp\/v2\/posts\/2813\/revisions"}],"predecessor-version":[{"id":2850,"href":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-json\/wp\/v2\/posts\/2813\/revisions\/2850"}],"wp:attachment":[{"href":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-json\/wp\/v2\/media?parent=2813"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-json\/wp\/v2\/categories?post=2813"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-json\/wp\/v2\/tags?post=2813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}