{"id":158,"date":"2020-06-26T14:55:11","date_gmt":"2020-06-26T12:55:11","guid":{"rendered":"http:\/\/www.oberberg-ist-bunt.org\/wordpress\/?p=158"},"modified":"2020-07-13T21:43:50","modified_gmt":"2020-07-13T19:43:50","slug":"75-jahre-vereinte-nationen","status":"publish","type":"post","link":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/75-jahre-vereinte-nationen\/","title":{"rendered":"75 Jahre Vereinte Nationen"},"content":{"rendered":"\n<p>Heute vor 75 Jahren, am 26. Juli 1945, wurde die Charta der Vereinten Nationen unterzeichnet.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"1015\" src=\"http:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2020\/06\/WE_THE_PEOPLES_OF_THE_UNITED_NATIONS_-_NARA_-_516086.jpg\" alt=\"\" class=\"wp-image-159\" srcset=\"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2020\/06\/WE_THE_PEOPLES_OF_THE_UNITED_NATIONS_-_NARA_-_516086.jpg 800w, https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2020\/06\/WE_THE_PEOPLES_OF_THE_UNITED_NATIONS_-_NARA_-_516086-236x300.jpg 236w, https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2020\/06\/WE_THE_PEOPLES_OF_THE_UNITED_NATIONS_-_NARA_-_516086-768x974.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p> In der Pr\u00e4ambel hei\u00dft es:<\/p>\n\n\n\n<p>WIR, DIE V\u00d6LKER DER VEREINTEN NATIONEN &#8211; FEST ENTSCHLOSSEN,<\/p>\n\n\n\n<p>k\u00fcnftige Geschlechter vor der Gei\u00dfel des Krieges zu bewahren, die zweimal zu unseren Lebzeiten unsagbares Leid \u00fcber die Menschheit gebracht hat,<\/p>\n\n\n\n<p>unseren Glauben an die Grundrechte des Menschen, an W\u00fcrde und Wert der menschlichen Pers\u00f6nlichkeit, an die Gleichberechtigung von Mann und Frau sowie von allen Nationen, ob gro\u00df oder klein, erneut zu bekr\u00e4ftigen,<\/p>\n\n\n\n<p>Bedingungen zu schaffen, unter denen Gerechtigkeit und die Achtung vor den Verpflichtungen aus Vertr\u00e4gen und anderen Quellen des V\u00f6lkerrechts gewahrt werden k\u00f6nnen,<\/p>\n\n\n\n<p>den sozialen Fortschritt und einen besseren Lebensstandard in gr\u00f6\u00dferer Freiheit zu f\u00f6rdern,<\/p>\n\n\n\n<p>UND F\u00dcR DIESE ZWECKE<\/p>\n\n\n\n<p>Duldsamkeit zu \u00fcben und als gute Nachbarn in Frieden miteinander zu leben,<\/p>\n\n\n\n<p>unsere Kr\u00e4fte zu vereinen, um den Weltfrieden und die internationale Sicherheit zu wahren,<\/p>\n\n\n\n<p>Grunds\u00e4tze anzunehmen und Verfahren einzuf\u00fchren, die gew\u00e4hrleisten, da\u00df Waffengewalt nur noch im gemeinsamen Interesse angewendet wird, internationale Einrichtungen in Anspruch zu nehmen, um den wirtschaftlichen und sozialen Fortschritt aller V\u00f6lker zu f\u00f6rdern &#8211;<\/p>\n\n\n\n<p>HABEN BESCHLOSSEN, IN UNSEREM BEM\u00dcHEN UM DIE ERREICHUNG DIESER ZIELE ZUSAMMENZUWIRKEN.<\/p>\n\n\n\n<p>Dementsprechend haben unsere Regierungen durch ihre in der Stadt San Franzisko versammelten Vertreter, deren Vollmachten vorgelegt und in guter und geh\u00f6riger Form befunden wurden, diese Charta der Vereinten Nationen angenommen und errichten hiermit eine internationale Organisation, die den Namen \u201eVereinte Nationen\u201c f\u00fchren soll.<\/p>\n\n\n\n<p>Der vollst\u00e4ndige Text der UN-Charta ist <a rel=\"noreferrer noopener\" href=\"https:\/\/unric.org\/de\/charta\/\" target=\"_blank\">hier<\/a> zu lesen.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Heute vor 75 Jahren, am 26. Juli 1945, wurde die Charta der Vereinten Nationen unterzeichnet. In der Pr\u00e4ambel hei\u00dft es: WIR, DIE V\u00d6LKER DER VEREINTEN NATIONEN &#8211; FEST ENTSCHLOSSEN, k\u00fcnftige Geschlechter vor der Gei\u00dfel des Krieges zu bewahren, die zweimal zu unseren Lebzeiten unsagbares Leid \u00fcber die Menschheit gebracht hat, unseren Glauben an die Grundrechte [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-158","post","type-post","status-publish","format-standard","hentry","category-allgemein"],"_links":{"self":[{"href":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-json\/wp\/v2\/posts\/158","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-json\/wp\/v2\/comments?post=158"}],"version-history":[{"count":1,"href":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-json\/wp\/v2\/posts\/158\/revisions"}],"predecessor-version":[{"id":160,"href":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-json\/wp\/v2\/posts\/158\/revisions\/160"}],"wp:attachment":[{"href":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-json\/wp\/v2\/media?parent=158"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-json\/wp\/v2\/categories?post=158"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-json\/wp\/v2\/tags?post=158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}