{"id":6082,"date":"2026-01-31T12:50:41","date_gmt":"2026-01-31T11:50:41","guid":{"rendered":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/?page_id=6082"},"modified":"2026-02-17T11:04:15","modified_gmt":"2026-02-17T10:04:15","slug":"nrw-appell-afd-verbot-jetzt","status":"publish","type":"page","link":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/nrw-appell-afd-verbot-jetzt\/","title":{"rendered":"NRW-Appell: AfD-Verbot JETZT"},"content":{"rendered":"\n<p>Der NRW-Appell f\u00fcr ein AfD-Verbot ist am ersten Februar-Wochenende 2026 gestartet. Wir wollen erreichen, dass die Landesregierung NRW im Bundesrat f\u00fcr ein Verbotsverfahren gegen die AfD eintritt. 70 prominente Menschen aus NRW unterst\u00fctzen den Appell und knapp 90 Gruppen aus ganz NRW haben beschlossen, die Kampagne zu unterst\u00fctzen und in den n\u00e4chsten Monaten f\u00fcr den Appell Unterschriften zu sammeln.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1810\" height=\"2560\" src=\"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2026\/02\/Plakat-DIN-A3-AfD-Verbot-Appell-NRW-RGB-scaled.jpg\" alt=\"\" class=\"wp-image-6145\" srcset=\"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2026\/02\/Plakat-DIN-A3-AfD-Verbot-Appell-NRW-RGB-scaled.jpg 1810w, https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2026\/02\/Plakat-DIN-A3-AfD-Verbot-Appell-NRW-RGB-212x300.jpg 212w, https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2026\/02\/Plakat-DIN-A3-AfD-Verbot-Appell-NRW-RGB-724x1024.jpg 724w, https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2026\/02\/Plakat-DIN-A3-AfD-Verbot-Appell-NRW-RGB-768x1086.jpg 768w, https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2026\/02\/Plakat-DIN-A3-AfD-Verbot-Appell-NRW-RGB-1086x1536.jpg 1086w, https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-content\/uploads\/2026\/02\/Plakat-DIN-A3-AfD-Verbot-Appell-NRW-RGB-1448x2048.jpg 1448w\" sizes=\"auto, (max-width: 1810px) 100vw, 1810px\" \/><\/figure>\n\n\n\n<p>Wir meinen, es ist dringend notwendig, dass der Antrag an das Bundesverfassungsgericht jetzt gestellt wird. Da es nach der letzten Wahl kaum noch zu erwarten ist, dass der Bundestag den Antrag stellt, ruht unsere Hoffnung jetzt auf dem Bundesrat. Und im Bundesrat hat NRW eine Schl\u00fcsselrolle. Zum einen, weil es sich um das bev\u00f6lkerungsreichste Bundesland handelt mit einem erheblichen Gewicht f\u00fcr die bundesdeutsche Diskussion und zum anderen, weil die Landesregierung \u2013 vor allem die hier regierende CDU noch gewinn- und \u00fcberzeugbar f\u00fcr diesen Weg zu sein scheint.<\/p>\n\n\n\n<p>Im politischen Kampf gegen Rassismus und gegen das menschenfeindliche Programm der AfD ist das Verbotsverfahren ein wichtiger Baustein zur Verteidigung von Demokratie und gegen autorit\u00e4re Entwicklungen. Und ein Blick in die Vergangenheit zeigt: Vor 1933 wurde es vers\u00e4umt, die NSDAP zu verbieten, obwohl es m\u00f6glich gewesen w\u00e4re &#8211; die schrecklichen Folgen wurden uns am Holocaust-Gedenktag noch einmal deutlich vor Augen gef\u00fchrt. Deshalb m\u00fcssen wir jetzt handeln! <strong>Unterschreibt, holt euch Listen und sammelt selber!<\/strong><\/p>\n\n\n\n<p>Listen k\u00f6nnen von der <a href=\"https:\/\/nrw-appell-afd-verbot.de\/\" target=\"_blank\" rel=\"noreferrer noopener\">Homepage des NRW-Appells<\/a> unter &#8222;<a href=\"https:\/\/nrw-appell-afd-verbot.de\/index.php\/materialien\/\">Materialien&#8220;<\/a> heruntergeladen werden.<\/p>\n\n\n\n<p><strong>Seit Freitag, 7.2.2026 &#8211; 12 Uhr, kann man auch die <a href=\"https:\/\/weact.campact.de\/p\/nrwappell\" target=\"_blank\" rel=\"noreferrer noopener\">Online-Petition zum NRW-Appell<\/a> unterzeichnen.<\/strong><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der NRW-Appell f\u00fcr ein AfD-Verbot ist am ersten Februar-Wochenende 2026 gestartet. Wir wollen erreichen, dass die Landesregierung NRW im Bundesrat f\u00fcr ein Verbotsverfahren gegen die AfD eintritt. 70 prominente Menschen aus NRW unterst\u00fctzen den Appell und knapp 90 Gruppen aus ganz NRW haben beschlossen, die Kampagne zu unterst\u00fctzen und in den n\u00e4chsten Monaten f\u00fcr den [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":4,"comment_status":"closed","ping_status":"closed","template":"","meta":{"gt_page_layout":"","gt_hide_page_title":false,"gt_remove_bottom_margin":false,"footnotes":""},"class_list":["post-6082","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-json\/wp\/v2\/pages\/6082","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-json\/wp\/v2\/comments?post=6082"}],"version-history":[{"count":5,"href":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-json\/wp\/v2\/pages\/6082\/revisions"}],"predecessor-version":[{"id":6146,"href":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-json\/wp\/v2\/pages\/6082\/revisions\/6146"}],"wp:attachment":[{"href":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-json\/wp\/v2\/media?parent=6082"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}