{"id":281,"date":"2020-08-22T21:22:54","date_gmt":"2020-08-22T19:22:54","guid":{"rendered":"http:\/\/www.oberberg-ist-bunt.org\/wordpress\/?page_id=281"},"modified":"2020-08-22T21:29:12","modified_gmt":"2020-08-22T19:29:12","slug":"2014-2","status":"publish","type":"page","link":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/2014-2\/","title":{"rendered":"2014"},"content":{"rendered":"\n<p><strong><a href=\"http:\/\/www.oberberg-ist-bunt.org\/wordpress\/?page_id=283\" target=\"_blank\" rel=\"noreferrer noopener\">November 2014: Informationen zur Partei &#8222;Die Rechte&#8220; in Oberberg<\/a><\/strong><\/p>\n\n\n\n<p><strong>Freundschaftsspiel gegen Rassismus<br><\/strong>Die IG Metall veranstaltet am 30. August in Wiehl ein Freundschaftsspiel gegen die Mannschaft der BPW<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><small><strong><a rel=\"noreferrer noopener\" href=\"http:\/\/www.oberberg-ist-bunt.org\/Hand_in_Hand.html\" target=\"_blank\">\u201eHAND IN HAND \u2013 gegen Rassismus, f\u00fcr Vielfalt und Toleranz\u201c<\/a>\u00a0war das Thema der Fotoaktion am 27. September 2014 beim Abschlussfest der Interkulturellen Woche.<\/strong><\/small><\/p>\n\n\n\n<p><strong>August 1914: Der Nationalismus st\u00fcrzt Europa in den Krieg<\/strong><br>Vor 100 Jahren begann der erste Weltkrieg. Gern wird die Ermordung eines Thronfolgers in Sarajevo als Ursache f\u00fcr den Krieg dargestellt \u2013 doch so einfach ist es nicht.<br>Es waren der deutsche und der \u00f6sterreich-ungarische Nationalismus und Militarismus, die diesen Krieg wollten und begonnen haben. Wer daran zweifelt, braucht sich nur einmal die Orte in Erinnerung zu rufen, an denen die entsetz\u00adlichen Schlachten zwischen 1914 und 1918 stattfanden: Verdun, die Somme \u2013 das ist in Frankreich und nicht bei uns. Wer hat also wen \u00fcberfallen?<br><a href=\"http:\/\/www.oberberg-ist-bunt.org\/August1914.pdf\">weiterlesen<\/a><\/p>\n\n\n\n<p><br><strong>Politisch motivierte Kriminalit\u00e4t Rechts im Oberbergischen<br><\/strong>In der Antwort auf eine Anfrage der Abgeordneten Verena Sch\u00e4fer hat der Landesinnenminister Zahlen zur \u201ePolitisch motivierten Kriminalit\u00e4t Rechts\u201c im Jahr 2013 zusammengestellt.<br>Wir haben die Zahlen f\u00fcr unseren Kreis herausgesucht:<br><a href=\"http:\/\/www.oberberg-ist-bunt.org\/StraftatenPMKRechts2013.pdf\">PMK Rechts 2013 in der Region<\/a><\/p>\n\n\n\n<p><strong>Wahlen am 25. Mai 2014<br>Die erste Botschaft muss nat\u00fcrlich lauten: W\u00c4HLEN GEHEN!<br>Wer nicht w\u00e4hlt, sichert den Rechtsextremisten h\u00f6here Prozentanteile<br><\/strong>Genauere Informationen zu den Parteien am rechten Rand, die im Oberbergischen auf den Stimmzetteln stehen, haben wir hier zusammengestellt:<br><a href=\"http:\/\/www.oberberg-ist-bunt.org\/Wahlen2014.pdf\">Information zu rechten Parteien bei den Wahlen am 25. Mai<\/a><\/p>\n\n\n\n<p><strong><br>20. April 2014: Neuer Name, alter Inhalt: \u201eDie Rechte\u201c statt \u201eFKOberberg\u201c<\/strong><\/p>\n\n\n\n<p>\u201eRaider hei\u00dft jetzt Twix \u2013 sonst \u00e4ndert sich nix\u201c \u2013 so hie\u00df ein Werbespruch in den 90er Jahren. Daran f\u00fchlt man sich erinnert, wenn man sich die aktuellen Umbr\u00fcche in der Neonazi-Szene im Kreis ansieht. Nach einigen Aktivit\u00e4ten Ende M\u00e4rz haben die \u201eFreien Kr\u00e4fte Oberberg\u201c pl\u00f6tzlich ihre \u201eAufl\u00f6sung\u201c bekannt gegeben. Leider sind die Rechtsextremisten nicht etwa zu der Erkenntnis gekommen, wie unsinnig und menschenverachtend ihre Einstellung ist. Sie haben sich lediglich (in Teilen) der Partei \u201eDie Rechte\u201c angeschlossen und einen \u201eKreisverband Oberberg\u201c gegr\u00fcndet. Dass es die selben Leute sind, erkennte man schon daran, dass die Webiste zun\u00e4chst den selben Header verwendet wie die FKOberberg. Inhaltlich steht noch nicht viel auf der Seite, nur die Gr\u00fcndungsversammlung \u201eim Raum Wiehl\u201c wird bekannt gegeben.<br>Zur Erinnerung: Die Partei \u201eDie Rechte\u201c ist bundesweit als Reaktion auf die Verbote verschiedener \u201eautonomer Kameradschaften\u201c gegr\u00fcndet worden. Inhaltlich und personell ist sie an vielen Orten indentisch mit den Kameradschaften, sie nutzt vor allem die besseren juristischen M\u00f6glichkeiten aus, die Parteien haben. Daf\u00fcr werden in der Sprache einige Aussagen umformuliert, um ein Verbot zu umgehen. Nun haben die oberbergischen Neonazis sich auch diese Form gegeben.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>November 2014: Informationen zur Partei &#8222;Die Rechte&#8220; in Oberberg Freundschaftsspiel gegen RassismusDie IG Metall veranstaltet am 30. August in Wiehl ein Freundschaftsspiel gegen die Mannschaft der BPW \u201eHAND IN HAND \u2013 gegen Rassismus, f\u00fcr Vielfalt und Toleranz\u201c\u00a0war das Thema der Fotoaktion am 27. September 2014 beim Abschlussfest der Interkulturellen Woche. August 1914: Der Nationalismus st\u00fcrzt [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":79,"comment_status":"closed","ping_status":"closed","template":"","meta":{"gt_page_layout":"","gt_hide_page_title":false,"gt_remove_bottom_margin":false,"footnotes":""},"class_list":["post-281","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-json\/wp\/v2\/pages\/281","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-json\/wp\/v2\/comments?post=281"}],"version-history":[{"count":2,"href":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-json\/wp\/v2\/pages\/281\/revisions"}],"predecessor-version":[{"id":285,"href":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-json\/wp\/v2\/pages\/281\/revisions\/285"}],"wp:attachment":[{"href":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-json\/wp\/v2\/media?parent=281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}