{"id":271,"date":"2020-08-22T20:53:15","date_gmt":"2020-08-22T18:53:15","guid":{"rendered":"http:\/\/www.oberberg-ist-bunt.org\/wordpress\/?page_id=271"},"modified":"2020-08-24T09:37:29","modified_gmt":"2020-08-24T07:37:29","slug":"januar-dezember-2016","status":"publish","type":"page","link":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/januar-dezember-2016\/","title":{"rendered":"2016"},"content":{"rendered":"\n<p><strong><a rel=\"noreferrer noopener\" target=\"_blank\" href=\"http:\/\/www.oberberg-ist-bunt.org\/Schritt-fuer-Schritt.html\">1. Oktober 2016:<\/a><\/strong><a rel=\"noreferrer noopener\" target=\"_blank\" href=\"http:\/\/www.oberberg-ist-bunt.org\/Schritt-fuer-Schritt.html\">\u00a0<strong>Fotoaktion \u201eSchritt f\u00fcr Schritt<\/strong><\/a>\u00a0\u2013 Aufeinander zu gehen \u2013 Gemeinsam gehen \u2013 Vorurteile \u00fcberwinden\u201c beim Abschlussfest der Interkulturellen Woche<\/p>\n\n\n\n<p><strong>1. September: Nie wieder Faschismus \u2013 Nie wieder Krieg!<\/strong><br>Am 1. September treffen wir uns um 18 Uhr im Wiehlpark am Friedensdenkstein zu einer Gedenkstunde.<br>Hier die <a href=\"http:\/\/www.oberberg-ist-bunt.org\/Flyer.pdf\"><strong>Einladung<\/strong><\/a>\u00a0und der\u00a0<a href=\"http:\/\/www.oberberg-ist-bunt.org\/DGB-Aufruf-zum-Antikriegstag-2016.pdf\"><strong>Aufruf des DGB<\/strong><\/a><\/p>\n\n\n\n<p><strong>August 2016: <\/strong>Die AfD Oberberg verk\u00fcndet, dass Marcus Pretzell im Hotel Victors in Gummersbach auftreten soll.<\/p>\n\n\n\n<p><strong><a href=\"http:\/\/www.oberberg-ist-bunt.org\/wordpress\/?page_id=273\">Erkl\u00e4rung unseres Vereins zum geplanten Pretzell-Auftritt<\/a><\/strong><\/p>\n\n\n\n<p><strong>24.8.2016:<\/strong><br>Die AfD Oberberg meldet, dass die Veranstaltung in anderen R\u00e4umen stattfindet. Den neuen Ort erfahren nur diejenigen, die sich bei der AfD angemeldet haben.<br>Danke an Victor\u2019s, dass sie der AfD den Raum gek\u00fcndigt haben!<br>Es ist ein gro\u00dfer Erfolg unseres Protestes, dass die Europ\u00e4ische Nationalisten-Fraktion nicht \u00f6ffentlich in Gummersbach einen Vortrag veranstalten kann!<\/p>\n\n\n\n<p><strong>28.8.2016:<\/strong><br>Nun haben die Europ\u00e4ischen Nationalisten also mehr oder weniger heimlich Herrn Pretzell von der AfD auftreten lassen \u2013 im eher kleineren Rahmen (wie man h\u00f6rt, hatte die AfD auch au\u00dferhalb von Oberberg ihre Leute f\u00fcr den Abend mobilisiert). Der Presseartikel l\u00e4sst vermuten, dass der Reporter wenig beeindruckt war von Pretzells Vortrag.<br><a rel=\"noreferrer noopener\" target=\"_blank\" href=\"http:\/\/www.oberberg-ist-bunt.org\/PresseartikelAfD-Pretzell-kommentiert.pdf\"><strong>Hier der Artikel (mit Kommentierung)<\/strong><\/a><\/p>\n\n\n\n<p><strong>18. Juni 2016: <a rel=\"noreferrer noopener\" href=\"http:\/\/www.oberberg-ist-bunt.org\/Menschenkette-18-6-2016.html\" data-type=\"URL\" data-id=\"http:\/\/www.oberberg-ist-bunt.org\/Menschenkette-18-6-2016.html\" target=\"_blank\">Unsere Menschenkette trotzte dem Regen!<\/a><\/strong><br>P\u00fcnktlich zu Beginn unserer Aktion \u201eHand in Hand gegen Rassismus \u2013 f\u00fcr Menschenrechte und Vielfalt\u201c machte uns der Himmel klar, dass wir zwar (fast) Sommer haben, aber dass wir schlie\u00dflich im Oberbergischen sind: Es fing an zu regnen. Nach kurzem Z\u00f6gern haben wir dann doch angefangen und unsere Kette durchgezogen. Denn eines ist klar: Wir lassen niemanden allein im Regen stehen \u2013 wir stellen uns einfach dazu! <\/p>\n\n\n\n<p><strong>23. Mai 2016:<\/strong> Am 18. Juni bilden wir die Menschenkette im Rahmen der Aktion<br><a href=\"http:\/\/www.oberberg-ist-bunt.org\/flyer-menschenkette-web.pdf\"><strong>Hand in Hand gegen Rassismus<\/strong><\/a><\/p>\n\n\n\n<p><strong>23. Mai 2016:<\/strong> Zum Tag des Grundgesetzes hier eine Erinnerung an<br>&nbsp;<a href=\"http:\/\/www.oberberg-ist-bunt.org\/Grundgesetz.pdf\"><strong>wichtige Passagen aus dem Grundgesetz<\/strong><\/a><\/p>\n\n\n\n<p><strong>20. M\u00e4rz 2016:<\/strong> Unser <strong>Beitrag zur bundesweiten Aktion \u201eHand in Hand gegen Rassismus&#8220; <\/strong>hat Freude gemacht. Die Lokalpresse hat einen sch\u00f6nen Bericht verfasst:<br>Fast alles richtig, aber wir machen nicht \u201eFriedenslieder statt Menschenketten\u201c, die Menschenketten sind (bundesweit) f\u00fcr den 19. Juni vorgesehen \u2013 da machen wir auch mit!<br><a rel=\"noreferrer noopener\" target=\"_blank\" href=\"http:\/\/www.rundschau-online.de\/region\/oberberg\/gummersbach\/aktion-gegen-rassismus-friedenslieder-in-der-gummersbacher-fussgaengerzone-23757498\"><strong>Hier der Artikel<\/strong><\/a><\/p>\n\n\n\n<p><strong>13.1.2016<\/strong><br>In der letzten Zeit heben wir die Aktualisierung dieser Seite zu Gunsten unserer Facebook-Seite schleifen lassen, deshalb kommen heute drei Meldungen auf einmal:<br><a rel=\"noreferrer noopener\" target=\"_blank\" href=\"http:\/\/www.oberberg-ist-bunt.org\/Januar2016.pdf\">Informationen zur Silvesternacht in K\u00f6ln und den Folgen<\/a><\/p>\n\n\n\n<p><a rel=\"noreferrer noopener\" target=\"_blank\" href=\"http:\/\/www.oberberg-ist-bunt.org\/Widerstand_gegen_Terror-Muslime_schuetzen_Christen.pdf\">Widerstand ist m\u00f6glich: muslimische Frauen sch\u00fctzen Christen vor Terror<\/a><br><a rel=\"noreferrer noopener\" target=\"_blank\" href=\"http:\/\/www.oberberg-ist-bunt.org\/updateWinter2015.pdf\">Informationen zur rechten Szene im Kreis (Stand Dezember 2015)<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>1. Oktober 2016:\u00a0Fotoaktion \u201eSchritt f\u00fcr Schritt\u00a0\u2013 Aufeinander zu gehen \u2013 Gemeinsam gehen \u2013 Vorurteile \u00fcberwinden\u201c beim Abschlussfest der Interkulturellen Woche 1. September: Nie wieder Faschismus \u2013 Nie wieder Krieg!Am 1. September treffen wir uns um 18 Uhr im Wiehlpark am Friedensdenkstein zu einer Gedenkstunde.Hier die Einladung\u00a0und der\u00a0Aufruf des DGB August 2016: Die AfD Oberberg verk\u00fcndet, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":82,"comment_status":"closed","ping_status":"closed","template":"","meta":{"gt_page_layout":"","gt_hide_page_title":false,"gt_remove_bottom_margin":false,"footnotes":""},"class_list":["post-271","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-json\/wp\/v2\/pages\/271","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-json\/wp\/v2\/comments?post=271"}],"version-history":[{"count":4,"href":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-json\/wp\/v2\/pages\/271\/revisions"}],"predecessor-version":[{"id":288,"href":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-json\/wp\/v2\/pages\/271\/revisions\/288"}],"wp:attachment":[{"href":"https:\/\/www.oberberg-ist-bunt.org\/wordpress\/wp-json\/wp\/v2\/media?parent=271"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}